{"id":500,"count":1,"description":"","link":"https:\/\/www.aljdwa.com\/en1\/tag\/%d8%aa%d9%82%d8%af%d9%8a%d8%b1-%d8%aa%d9%83%d8%a7%d9%84%d9%8a%d9%81-%d8%a7%d9%84%d9%85%d8%b4%d8%b1%d9%88%d8%b9\/","name":"\u062a\u0642\u062f\u064a\u0631 \u062a\u0643\u0627\u0644\u064a\u0641 \u0627\u0644\u0645\u0634\u0631\u0648\u0639","slug":"%d8%aa%d9%82%d8%af%d9%8a%d8%b1-%d8%aa%d9%83%d8%a7%d9%84%d9%8a%d9%81-%d8%a7%d9%84%d9%85%d8%b4%d8%b1%d9%88%d8%b9","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.4 (Yoast SEO v24.4) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u062a\u0642\u062f\u064a\u0631 \u062a\u0643\u0627\u0644\u064a\u0641 \u0627\u0644\u0645\u0634\u0631\u0648\u0639 - \u0627\u0644\u062c\u062f\u0648\u0649 Aljdwa<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u062a\u0642\u062f\u064a\u0631 \u062a\u0643\u0627\u0644\u064a\u0641 \u0627\u0644\u0645\u0634\u0631\u0648\u0639 \u0627\u0644\u0623\u0631\u0634\u064a\u0641\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aljdwa.com\/en1\/tag\/\u062a\u0642\u062f\u064a\u0631-\u062a\u0643\u0627\u0644\u064a\u0641-\u0627\u0644\u0645\u0634\u0631\u0648\u0639\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0627\u0644\u062c\u062f\u0648\u0649 Aljdwa\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aljdwa.com\/wp-content\/uploads\/2020\/08\/Screen-Shot-2020-08-28-at-12.48.06-AM.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2408\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@feasibility_s\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.aljdwa.com\/en1\/tag\/%d8%aa%d9%82%d8%af%d9%8a%d8%b1-%d8%aa%d9%83%d8%a7%d9%84%d9%8a%d9%81-%d8%a7%d9%84%d9%85%d8%b4%d8%b1%d9%88%d8%b9\/\",\"url\":\"https:\/\/www.aljdwa.com\/en1\/tag\/%d8%aa%d9%82%d8%af%d9%8a%d8%b1-%d8%aa%d9%83%d8%a7%d9%84%d9%8a%d9%81-%d8%a7%d9%84%d9%85%d8%b4%d8%b1%d9%88%d8%b9\/\",\"name\":\"\u062a\u0642\u062f\u064a\u0631 \u062a\u0643\u0627\u0644\u064a\u0641 \u0627\u0644\u0645\u0634\u0631\u0648\u0639 - \u0627\u0644\u062c\u062f\u0648\u0649 Aljdwa\",\"isPartOf\":{\"@id\":\"https:\/\/www.aljdwa.com\/en1\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.aljdwa.com\/en1\/tag\/%d8%aa%d9%82%d8%af%d9%8a%d8%b1-%d8%aa%d9%83%d8%a7%d9%84%d9%8a%d9%81-%d8%a7%d9%84%d9%85%d8%b4%d8%b1%d9%88%d8%b9\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.aljdwa.com\/en1\/tag\/%d8%aa%d9%82%d8%af%d9%8a%d8%b1-%d8%aa%d9%83%d8%a7%d9%84%d9%8a%d9%81-%d8%a7%d9%84%d9%85%d8%b4%d8%b1%d9%88%d8%b9\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629\",\"item\":\"https:\/\/www.aljdwa.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u062a\u0642\u062f\u064a\u0631 \u062a\u0643\u0627\u0644\u064a\u0641 \u0627\u0644\u0645\u0634\u0631\u0648\u0639\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.aljdwa.com\/en1\/#website\",\"url\":\"https:\/\/www.aljdwa.com\/en1\/\",\"name\":\"\u0627\u0644\u062c\u062f\u0648\u0649 Aljdwa\",\"description\":\"\u0627\u0644\u0634\u0631\u0643\u0629 \u0627\u0644\u0633\u0639\u0648\u062f\u064a\u0629 \u0627\u0644\u0631\u0627\u0626\u062f\u0629 \u0641\u064a \u0625\u0639\u062f\u0627\u062f \u062f\u0631\u0627\u0633\u0629 \u062c\u062f\u0648\u0649 \u0645\u0634\u0631\u0648\u0639\u0643 \u0648\u062a\u0637\u0648\u064a\u0631\u0647\",\"publisher\":{\"@id\":\"https:\/\/www.aljdwa.com\/en1\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.aljdwa.com\/en1\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.aljdwa.com\/en1\/#organization\",\"name\":\"\u0627\u0644\u062c\u062f\u0648\u0649\",\"url\":\"https:\/\/www.aljdwa.com\/en1\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.aljdwa.com\/en1\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.aljdwa.com\/wp-content\/uploads\/2020\/08\/logo-2.png\",\"contentUrl\":\"https:\/\/www.aljdwa.com\/wp-content\/uploads\/2020\/08\/logo-2.png\",\"width\":486,\"height\":355,\"caption\":\"\u0627\u0644\u062c\u062f\u0648\u0649\"},\"image\":{\"@id\":\"https:\/\/www.aljdwa.com\/en1\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/feasibility_s\",\"https:\/\/www.instagram.com\/feasibility_s\/?hl=ar\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u062a\u0642\u062f\u064a\u0631 \u062a\u0643\u0627\u0644\u064a\u0641 \u0627\u0644\u0645\u0634\u0631\u0648\u0639 - \u0627\u0644\u062c\u062f\u0648\u0649 Aljdwa","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"\u062a\u0642\u062f\u064a\u0631 \u062a\u0643\u0627\u0644\u064a\u0641 \u0627\u0644\u0645\u0634\u0631\u0648\u0639 \u0627\u0644\u0623\u0631\u0634\u064a\u0641","og_url":"https:\/\/www.aljdwa.com\/en1\/tag\/\u062a\u0642\u062f\u064a\u0631-\u062a\u0643\u0627\u0644\u064a\u0641-\u0627\u0644\u0645\u0634\u0631\u0648\u0639\/","og_site_name":"\u0627\u0644\u062c\u062f\u0648\u0649 Aljdwa","og_image":[{"width":2408,"height":768,"url":"https:\/\/www.aljdwa.com\/wp-content\/uploads\/2020\/08\/Screen-Shot-2020-08-28-at-12.48.06-AM.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@feasibility_s","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.aljdwa.com\/en1\/tag\/%d8%aa%d9%82%d8%af%d9%8a%d8%b1-%d8%aa%d9%83%d8%a7%d9%84%d9%8a%d9%81-%d8%a7%d9%84%d9%85%d8%b4%d8%b1%d9%88%d8%b9\/","url":"https:\/\/www.aljdwa.com\/en1\/tag\/%d8%aa%d9%82%d8%af%d9%8a%d8%b1-%d8%aa%d9%83%d8%a7%d9%84%d9%8a%d9%81-%d8%a7%d9%84%d9%85%d8%b4%d8%b1%d9%88%d8%b9\/","name":"\u062a\u0642\u062f\u064a\u0631 \u062a\u0643\u0627\u0644\u064a\u0641 \u0627\u0644\u0645\u0634\u0631\u0648\u0639 - \u0627\u0644\u062c\u062f\u0648\u0649 Aljdwa","isPartOf":{"@id":"https:\/\/www.aljdwa.com\/en1\/#website"},"breadcrumb":{"@id":"https:\/\/www.aljdwa.com\/en1\/tag\/%d8%aa%d9%82%d8%af%d9%8a%d8%b1-%d8%aa%d9%83%d8%a7%d9%84%d9%8a%d9%81-%d8%a7%d9%84%d9%85%d8%b4%d8%b1%d9%88%d8%b9\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aljdwa.com\/en1\/tag\/%d8%aa%d9%82%d8%af%d9%8a%d8%b1-%d8%aa%d9%83%d8%a7%d9%84%d9%8a%d9%81-%d8%a7%d9%84%d9%85%d8%b4%d8%b1%d9%88%d8%b9\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629","item":"https:\/\/www.aljdwa.com\/"},{"@type":"ListItem","position":2,"name":"\u062a\u0642\u062f\u064a\u0631 \u062a\u0643\u0627\u0644\u064a\u0641 \u0627\u0644\u0645\u0634\u0631\u0648\u0639"}]},{"@type":"WebSite","@id":"https:\/\/www.aljdwa.com\/en1\/#website","url":"https:\/\/www.aljdwa.com\/en1\/","name":"\u0627\u0644\u062c\u062f\u0648\u0649 Aljdwa","description":"The leading Saudi company in preparing your project's feasibility study and development.","publisher":{"@id":"https:\/\/www.aljdwa.com\/en1\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aljdwa.com\/en1\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.aljdwa.com\/en1\/#organization","name":"Feasibility","url":"https:\/\/www.aljdwa.com\/en1\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.aljdwa.com\/en1\/#\/schema\/logo\/image\/","url":"https:\/\/www.aljdwa.com\/wp-content\/uploads\/2020\/08\/logo-2.png","contentUrl":"https:\/\/www.aljdwa.com\/wp-content\/uploads\/2020\/08\/logo-2.png","width":486,"height":355,"caption":"\u0627\u0644\u062c\u062f\u0648\u0649"},"image":{"@id":"https:\/\/www.aljdwa.com\/en1\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/feasibility_s","https:\/\/www.instagram.com\/feasibility_s\/?hl=ar"]}]}},"lang":"ar","translations":{"ar":500},"_links":{"self":[{"href":"https:\/\/www.aljdwa.com\/en1\/wp-json\/wp\/v2\/tags\/500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aljdwa.com\/en1\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.aljdwa.com\/en1\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.aljdwa.com\/en1\/wp-json\/wp\/v2\/posts?tags=500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}